﻿{"id":112091,"date":"2020-01-29T18:16:44","date_gmt":"2020-01-29T17:16:44","guid":{"rendered":"https:\/\/www.superprof.es\/diccionario\/analitica\/excentricidad.html"},"modified":"2020-01-29T18:16:44","modified_gmt":"2020-01-29T17:16:44","slug":"excentricidad","status":"publish","type":"post","link":"https:\/\/www.superprof.es\/diccionario\/matematicas\/analitica\/excentricidad.html","title":{"rendered":"Excentricidad"},"content":{"rendered":"<section id=\"sec\" style=\"\">\n<h3 class=\"r\" style=\"clear:left; text-align:left; margin-left:5%;\">Excentricidad de la elipse<\/h3>\n<p class=\"\">La <strong>excentricidad<\/strong> es un n\u00famero que mide el mayor o menor achatamiento de la elipse. Y es igual al cociente entre su semidistancia focal y su semieje mayor.<\/p>\n<p class=\"actividades_2_v\"><img decoding=\"async\" src=\"https:\/\/www.superprof.es\/diccionario\/wp-content\/uploads\/2020\/01\/excentricidad-1.gif\" alt=\"Explicaciones y ejemplos de excentricidad - 1\"  ><\/p>\n<div class=\"principal\">\n<div class=\"left\" style=\"\"><img decoding=\"async\" src=\"https:\/\/www.superprof.es\/diccionario\/wp-content\/uploads\/2020\/01\/excentricidad-2.gif\" alt=\"Explicaciones y ejemplos de excentricidad - 2\"  ><\/div>\n<p style=\"\" class=\"ar\"><img decoding=\"async\" src=\"https:\/\/www.superprof.es\/diccionario\/wp-content\/uploads\/2020\/01\/excentricidad-3.gif\" alt=\"Explicaciones y ejemplos de excentricidad - 3\"  ><\/p>\n<p style=\"\" class=\"av\"><img decoding=\"async\" src=\"https:\/\/www.superprof.es\/diccionario\/wp-content\/uploads\/2020\/01\/excentricidad-4.gif\" alt=\"Explicaciones y ejemplos de excentricidad - 4\"  ><\/p>\n<\/p><\/div>\n<div class=\"principal\">\n<div class=\"left\" style=\"\"><img decoding=\"async\" src=\"https:\/\/www.superprof.es\/diccionario\/wp-content\/uploads\/2020\/01\/excentricidad-5.gif\" alt=\"Explicaciones y ejemplos de excentricidad - 5\"  ><\/div>\n<p style=\"\" class=\"av\"><img decoding=\"async\" src=\"https:\/\/www.superprof.es\/diccionario\/wp-content\/uploads\/2020\/01\/excentricidad-6.gif\" alt=\"Explicaciones y ejemplos de excentricidad - 6\"  ><\/p>\n<\/p><\/div>\n<div class=\"principal\">\n<div class=\"left\" style=\"\"><img decoding=\"async\" src=\"https:\/\/www.superprof.es\/diccionario\/wp-content\/uploads\/2020\/01\/excentricidad-7.gif\" alt=\"Explicaciones y ejemplos de excentricidad - 7\"  ><\/div>\n<p style=\"\" class=\"av\"><img decoding=\"async\" src=\"https:\/\/www.superprof.es\/diccionario\/wp-content\/uploads\/2020\/01\/excentricidad-8.gif\" alt=\"Explicaciones y ejemplos de excentricidad - 8\"  ><\/p>\n<\/p><\/div>\n<div class=\"principal\">\n<div class=\"left\" style=\"\"><img decoding=\"async\" src=\"https:\/\/www.superprof.es\/diccionario\/wp-content\/uploads\/2020\/01\/excentricidad-9.gif\" alt=\"Explicaciones y ejemplos de excentricidad - 9\"  ><\/div>\n<p style=\"\" class=\"ar\"><img decoding=\"async\" src=\"https:\/\/www.superprof.es\/diccionario\/wp-content\/uploads\/2020\/01\/excentricidad-10.gif\" alt=\"Explicaciones y ejemplos de excentricidad - 10\"  ><\/p>\n<p style=\"\" class=\"av\"><img decoding=\"async\" src=\"https:\/\/www.superprof.es\/diccionario\/wp-content\/uploads\/2020\/01\/excentricidad-11.gif\" alt=\"Explicaciones y ejemplos de excentricidad - 11\" width=\"94\" \/><\/p>\n<h2 class=\"r\">Excentricidad de la hip\u00e9rbola<\/h2>\n<p class=\"\">La excentricidad mide la abertura mayor o menor de las ramas de la hip\u00e9rbola.<\/p>\n<p class=\"actividades_2_v\"><img decoding=\"async\" src=\"https:\/\/www.superprof.es\/diccionario\/wp-content\/uploads\/2020\/01\/excentricidad-12.gif\" alt=\"Explicaciones y ejemplos de excentricidad - 12\"  ><\/p>\n<div class=\"principal\">\n<div class=\"left\" style=\"\"><img decoding=\"async\" src=\"https:\/\/www.superprof.es\/diccionario\/wp-content\/uploads\/2020\/01\/excentricidad-13.gif\" alt=\"Explicaciones y ejemplos de excentricidad - 13\"  >\t\t\t\t\t\t\t\t<\/div>\n<p style=\"\" class=\"av\"><img decoding=\"async\" src=\"https:\/\/www.superprof.es\/diccionario\/wp-content\/uploads\/2020\/01\/excentricidad-14.gif\" alt=\"Explicaciones y ejemplos de excentricidad - 14\"  ><\/p>\n<\/p><\/div>\n<div class=\"principal\">\n<div class=\"left\" style=\"\"><img decoding=\"async\" src=\"https:\/\/www.superprof.es\/diccionario\/wp-content\/uploads\/2020\/01\/excentricidad-15.gif\" alt=\"Explicaciones y ejemplos de excentricidad - 15\"  >\t\t\t\t\t\t\t\t<\/div>\n<p style=\"\" class=\"av\"><img decoding=\"async\" src=\"https:\/\/www.superprof.es\/diccionario\/wp-content\/uploads\/2020\/01\/excentricidad-16.gif\" alt=\"Explicaciones y ejemplos de excentricidad - 16\"  ><\/p>\n<p style=\"\" class=\"ar\"><img decoding=\"async\" src=\"https:\/\/www.superprof.es\/diccionario\/wp-content\/uploads\/2020\/01\/excentricidad-17.gif\" alt=\"Explicaciones y ejemplos de excentricidad - 17\"  ><\/p>\n<\/p><\/div>\n<div class=\"principal\">\n<div class=\"left\" style=\"\"><img decoding=\"async\" src=\"https:\/\/www.superprof.es\/diccionario\/wp-content\/uploads\/2020\/01\/excentricidad-18.gif\" alt=\"Explicaciones y ejemplos de excentricidad - 18\"  >\t\t\t\t\t\t\t\t<\/div>\n<p style=\"\" class=\"av\"><img decoding=\"async\" src=\"https:\/\/www.superprof.es\/diccionario\/wp-content\/uploads\/2020\/01\/excentricidad-19.gif\" alt=\"Explicaciones y ejemplos de excentricidad - 19\"   ><\/p>\n<\/p><\/div>\n<div class=\"principal\">\n<div class=\"left\" style=\"\"><img decoding=\"async\" src=\"https:\/\/www.superprof.es\/diccionario\/wp-content\/uploads\/2020\/01\/excentricidad-20.gif\" alt=\"Explicaciones y ejemplos de excentricidad - 20\"  >\t\t\t\t\t\t\t\t<\/div>\n<p style=\"\" class=\"av\"><img decoding=\"async\" src=\"https:\/\/www.superprof.es\/diccionario\/wp-content\/uploads\/2020\/01\/excentricidad-21.gif\" alt=\"Explicaciones y ejemplos de excentricidad - 21\"  ><\/p>\n<\/p><\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>Excentricidad de la elipse La excentricidad es un n\u00famero que mide el mayor o menor achatamiento de la elipse. Y es igual al cociente entre su semidistancia focal y su semieje mayor. Excentricidad de la hip\u00e9rbola La excentricidad mide la abertura mayor o menor de las ramas de la hip\u00e9rbola.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[376],"tags":[375],"class_list":["post-112091","post","type-post","status-publish","format-standard","hentry","category-analitica","tag-e"],"acf":[],"author_meta":{"display_name":"Andra","author_link":"https:\/\/www.superprof.es\/diccionario\/author\/andra"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/www.superprof.es\/diccionario\/matematicas\/analitica\" class=\"advgb-post-tax-term\">Anal\u00edtica<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Anal\u00edtica<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/www.superprof.es\/diccionario\/matematicas\/analitica\" class=\"advgb-post-tax-term\">e<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">e<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 7 a\u00f1os hace","modified":"Actualizado 7 a\u00f1os hace"},"absolute_dates":{"created":"Publicado el 29 enero 2020","modified":"Actualizado el 29 enero 2020"},"absolute_dates_time":{"created":"Publicado el 29 enero 2020 18 h 16 min","modified":"Actualizado el 29 enero 2020 18 h 16 min"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/www.superprof.es\/diccionario\/wp-json\/wp\/v2\/posts\/112091","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.superprof.es\/diccionario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.superprof.es\/diccionario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.superprof.es\/diccionario\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.superprof.es\/diccionario\/wp-json\/wp\/v2\/comments?post=112091"}],"version-history":[{"count":0,"href":"https:\/\/www.superprof.es\/diccionario\/wp-json\/wp\/v2\/posts\/112091\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.superprof.es\/diccionario\/wp-json\/wp\/v2\/media?parent=112091"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.superprof.es\/diccionario\/wp-json\/wp\/v2\/categories?post=112091"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.superprof.es\/diccionario\/wp-json\/wp\/v2\/tags?post=112091"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}